{"id":9610,"date":"2025-09-22T12:03:08","date_gmt":"2025-09-22T15:03:08","guid":{"rendered":"http:\/\/10.6.206.88\/portal\/?p=9610"},"modified":"2025-09-22T12:04:59","modified_gmt":"2025-09-22T15:04:59","slug":"hospital-base-valdivia-realiza-exitosa-cirugia-con-tecnica-minimamente-invasiva-en-paciente-con-tumor-nasal","status":"publish","type":"post","link":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/2025\/09\/22\/hospital-base-valdivia-realiza-exitosa-cirugia-con-tecnica-minimamente-invasiva-en-paciente-con-tumor-nasal\/","title":{"rendered":"Hospital Base Valdivia realiza exitosa cirug\u00eda con t\u00e9cnica m\u00ednimamente invasiva en paciente con tumor nasal"},"content":{"rendered":"<ul>\n<li><b>La intervenci\u00f3n permiti\u00f3 extirpar el tumor sin cicatrices visibles y con una recuperaci\u00f3n m\u00e1s r\u00e1pida para el paciente, gracias al uso de tecnolog\u00eda avanzada y al trabajo colaborativo entre especialistas de Valdivia y Temuco.<\/b><\/li>\n<\/ul>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-9611\" src=\"http:\/\/10.6.206.88\/portal\/wp-content\/uploads\/2025\/09\/Equipo.jpeg\" alt=\"\" width=\"1352\" height=\"1066\" srcset=\"https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2025\/09\/Equipo.jpeg 1352w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2025\/09\/Equipo-300x237.jpeg 300w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2025\/09\/Equipo-1024x807.jpeg 1024w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2025\/09\/Equipo-254x200.jpeg 254w\" sizes=\"(max-width: 1352px) 100vw, 1352px\" \/><\/p>\n<p>El\u00a0Hospital\u00a0Base Valdivia (HBV) alcanz\u00f3 un importante hito al realizar, por primera vez, una cirug\u00eda endosc\u00f3pica nasal que permiti\u00f3 extirpar con \u00e9xito un tumor ubicado en la zona cercana al ojo de un paciente de 31 a\u00f1os. Esta intervenci\u00f3n, m\u00ednimamente invasiva, evita incisiones cut\u00e1neas\u00a0\u00a0 externas y cicatrices visibles, ofreciendo una recuperaci\u00f3n m\u00e1s r\u00e1pida y segura.<\/p>\n<p>La cirug\u00eda fue liderada por el Dr. Diego Navarro, otorrinolaring\u00f3logo del\u00a0Hospital\u00a0Base Valdivia, junto al Dr. Germ\u00e1n Segu\u00ed, tambi\u00e9n especialista en otorrinolaringolog\u00eda del HBV. El procedimiento cont\u00f3 adem\u00e1s con la colaboraci\u00f3n del Dr. Miguel Henr\u00edquez, otorrinolaring\u00f3logo del\u00a0Hospital\u00a0Dr. Hern\u00e1n Henr\u00edquez Aravena, quien aport\u00f3 su experiencia como apoyo y gu\u00eda en esta intervenci\u00f3n de alta complejidad, la cual, si no se trata oportunamente, puede generar complicaciones graves como invasi\u00f3n intracraneal o afectaci\u00f3n de la visi\u00f3n.<\/p>\n<p>El Dr. Navarro destac\u00f3 que esta t\u00e9cnica marca un importante avance para la salud p\u00fablica en el sur del pa\u00eds. \u201cEstamos muy satisfechos con el resultado de la cirug\u00eda, que fue posible gracias a la preparaci\u00f3n del equipo y al uso de nuevas herramientas. Hoy contamos con un equipo de otorrinolaringolog\u00eda cada vez m\u00e1s especializado, junto con instrumentales de \u00faltima generaci\u00f3n que nos permiten acceder a zonas de dif\u00edcil exploraci\u00f3n. A esto se sum\u00f3, por primera vez, la utilizaci\u00f3n de un Neuronavegador en cirug\u00eda de base de cr\u00e1neo anterior. Este dispositivo permite integrar im\u00e1genes de esc\u00e1ner en tiempo real para aportar un nivel extra de precisi\u00f3n y seguridad durante la intervenci\u00f3n quir\u00fargica\u201d.<\/p>\n<p>Asimismo, destac\u00f3 que \u201ccontar con la experiencia del Dr. Henr\u00edquez fue clave para establecer un trabajo colaborativo entre Valdivia y Temuco, lo que en el futuro nos permitir\u00e1 llevar a cabo procedimientos de mayor complejidad en nuestra ciudad. Su apoyo sienta un precedente importante, que nos abre la posibilidad de desarrollar este tipo de intervenciones de manera regular en Valdivia en el mediano plazo\u201d.<\/p>\n<p><strong>Experiencia compartida<\/strong><\/p>\n<p>Para el Dr. Henr\u00edquez, la invitaci\u00f3n a participar en esta cirug\u00eda tuvo un significado especial, ya que \u201cfue muy especial volver a Valdivia, la ciudad donde estudi\u00e9 medicina, y poder colaborar en una cirug\u00eda de base de cr\u00e1neo anterior junto al gran equipo humano del\u00a0Hospital\u00a0Base\u201d.<\/p>\n<p>Agreg\u00f3 que \u201ccon la tecnolog\u00eda disponible y la motivaci\u00f3n de sus profesionales, estoy seguro de que vendr\u00e1n muchas m\u00e1s cirug\u00edas avanzadas de rinolog\u00eda y base de cr\u00e1neo, que beneficiar\u00e1n directamente a los pacientes de la regi\u00f3n\u201d.<\/p>\n<p><strong>El testimonio del paciente<\/strong><\/p>\n<p>Posterior a su control post operatorio, Francisco Fett, paciente intervenido, destac\u00f3 los resultados de la cirug\u00eda, se\u00f1alando que \u201cfue una operaci\u00f3n poco invasiva, sin cicatrices ni complicaciones. A pesar de haber sido una intervenci\u00f3n larga, la recuperaci\u00f3n ha sido r\u00e1pida: en solo una semana ya pude retomar mi vida normal\u201d.<\/p>\n<p>\u201cSoy paciente asm\u00e1tico, y esta condici\u00f3n me causaba mucosidad, alergias, tos y dificultades para dormir. Desde la operaci\u00f3n, estos s\u00edntomas han disminuido notablemente y espero que sigan mejorando. Adem\u00e1s, el ojo izquierdo ya recuper\u00f3 su posici\u00f3n normal, y ahora siento que respiro mucho mejor, lo que realmente hace una gran diferencia en mi vida diaria. Estoy muy agradecido del doctor, del equipo m\u00e9dico y de la forma en que siempre estuvieron presentes y comunicativos\u201d, agreg\u00f3 el usuario.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-9612 size-large\" src=\"http:\/\/10.6.206.88\/portal\/wp-content\/uploads\/2025\/09\/Beneficiario-1024x768.jpeg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2025\/09\/Beneficiario-1024x768.jpeg 1024w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2025\/09\/Beneficiario-300x225.jpeg 300w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2025\/09\/Beneficiario-267x200.jpeg 267w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2025\/09\/Beneficiario.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La intervenci\u00f3n permiti\u00f3 extirpar el tumor sin cicatrices visibles y con una recuperaci\u00f3n m\u00e1s r\u00e1pida para el paciente, gracias al uso de tecnolog\u00eda avanzada y al trabajo colaborativo entre especialistas de Valdivia y Temuco. El\u00a0Hospital\u00a0Base Valdivia (HBV) alcanz\u00f3 un importante hito al realizar, por primera vez, una cirug\u00eda endosc\u00f3pica nasal que permiti\u00f3 extirpar con \u00e9xito [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":9614,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[56,5],"tags":[],"class_list":["post-9610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacada","category-noticias"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2025\/09\/Equipo-1.jpeg",1352,1066,false],"thumbnail":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2025\/09\/Equipo-1-150x150.jpeg",150,150,true],"medium":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2025\/09\/Equipo-1-300x237.jpeg",300,237,true],"medium_large":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2025\/09\/Equipo-1.jpeg",1352,1066,false],"large":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2025\/09\/Equipo-1-1024x807.jpeg",1024,807,true],"1536x1536":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2025\/09\/Equipo-1.jpeg",1352,1066,false],"2048x2048":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2025\/09\/Equipo-1.jpeg",1352,1066,false],"list_articles_thumbs":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2025\/09\/Equipo-1-400x400.jpeg",400,400,true],"slider_thumbs":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2025\/09\/Equipo-1-254x200.jpeg",254,200,true]},"uagb_author_info":{"display_name":"Barbara Vega","author_link":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/author\/barbara-vega-ssvredsalud-gob-cl\/"},"uagb_comment_info":0,"uagb_excerpt":"La intervenci\u00f3n permiti\u00f3 extirpar el tumor sin cicatrices visibles y con una recuperaci\u00f3n m\u00e1s r\u00e1pida para el paciente, gracias al uso de tecnolog\u00eda avanzada y al trabajo colaborativo entre especialistas de Valdivia y Temuco. El\u00a0Hospital\u00a0Base Valdivia (HBV) alcanz\u00f3 un importante hito al realizar, por primera vez, una cirug\u00eda endosc\u00f3pica nasal que permiti\u00f3 extirpar con \u00e9xito&hellip;","_links":{"self":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts\/9610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/comments?post=9610"}],"version-history":[{"count":1,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts\/9610\/revisions"}],"predecessor-version":[{"id":9613,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts\/9610\/revisions\/9613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/media\/9614"}],"wp:attachment":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/media?parent=9610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/categories?post=9610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/tags?post=9610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}