{"id":640,"date":"2016-05-13T22:36:59","date_gmt":"2016-05-13T22:36:59","guid":{"rendered":"http:\/\/10.6.67.9\/?p=640"},"modified":"2016-05-13T22:37:46","modified_gmt":"2016-05-13T22:37:46","slug":"prevalencia-de-co-factores-asociados-a-la-infeccion-por-helicobacter-pylori-hp-en-zonas-de-alto-y-bajo-riesgo-de-cancer-gastrico-2","status":"publish","type":"post","link":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/2016\/05\/13\/prevalencia-de-co-factores-asociados-a-la-infeccion-por-helicobacter-pylori-hp-en-zonas-de-alto-y-bajo-riesgo-de-cancer-gastrico-2\/","title":{"rendered":"\u201cPrevalencia de Co-factores asociados a la Infecci\u00f3n por Helicob\u00e1cter pylori (Hp) en zonas de alto y bajo riesgo de C\u00e1ncer G\u00e1strico\u201d"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>El proyecto consiste en una investigaci\u00f3n comparativa entre la ciudad de Valdivia y la ciudad de Antofagasta, con el objetivo de identificar la presencia de C\u00e1ncer G\u00e1strico asociado a la infecci\u00f3n por Helicobacter pylori, en ambas ciudades.<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-641 aligncenter\" src=\"http:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/foto-hp.jpg\" alt=\"foto hp\" width=\"1000\" height=\"463\" srcset=\"https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/foto-hp.jpg 1000w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/foto-hp-300x139.jpg 300w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/foto-hp-768x356.jpg 768w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/foto-hp-432x200.jpg 432w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">La Unidad de Epidemiolog\u00eda del Hospital Base Valdivia en conjunto con la Pontificia Universidad Cat\u00f3lica de Chile, Universidad de Antofagasta, Universidad Austral de Chile y la Agencia Internacional de C\u00e1ncer de la OMS, llevan a cabo un proyecto aprobado por la Comisi\u00f3n Nacional de Investigaci\u00f3n Cient\u00edfica y Tecnol\u00f3gica -Ministerio de Salud (FONIS) denominado \u201cPrevalencia de Co-factores asociados a la Infecci\u00f3n por Helicob\u00e1cter pylori (Hp) en zonas de alto y bajo riesgo de C\u00e1ncer G\u00e1strico\u201d<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">El proyecto consiste en una investigaci\u00f3n comparativa entre la ciudad de Valdivia y la ciudad de Antofagasta, con el objetivo de identificar porqu\u00e9 en Chile existen zonas de alta infecci\u00f3n por Helicobacter pylori (Hp) y baja presencia de c\u00e1ncer g\u00e1strico, como el caso de Antofagasta, y porqu\u00e9 existen otras zonas como Valdivia, donde tanto la presencia de Hp como el c\u00e1ncer g\u00e1strico son de alta magnitud. Esta es una problem\u00e1tica de alta relevancia dado que el Helicobacter pylori (Hp) es una causa necesaria de la mayor\u00eda de los c\u00e1nceres g\u00e1stricos especialmente cuando la infecci\u00f3n se adquiere en la infancia.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Esta investigaci\u00f3n es dirigida por Dra. Catterina Ferreccio, Epidemi\u00f3loga de la Pontificia Universidad Cat\u00f3lica de Chile y a nivel local por Dra. Katy Heise Mora Jefe de la Unidad de Epidemiologia del Hospital Base Valdivia, participando adem\u00e1s la Universidad Austral de Chile a trav\u00e9s del Instituto de Bioqu\u00edmica y Microbiolog\u00eda, Universidad de Antofagasta y la Agencia Internacional del C\u00e1ncer de la Organizaci\u00f3n Mundial de la Salud.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\u201cEl resultado de este estudio nos permitir\u00e1 proponer intervenciones a nivel poblacional as\u00ed como tambi\u00e9n intervenciones cl\u00ednicas, que contribuyan a reducir el riesgo de c\u00e1ncer g\u00e1strico\u201d explic\u00f3 Paz Cook, Enfermera Epidemi\u00f3loga, Coordinadora de investigaci\u00f3n de la Pontificia Universidad Cat\u00f3lica de Chile.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong>Visita de los investigadores<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">El pasado 28 de mayo la Directora del Mag\u00edster en Epidemiolog\u00eda de la UC, Dra. Catterina Ferreccio visit\u00f3 el Hospital para revisar en terreno el proceso de investigaci\u00f3n, quien adem\u00e1s explic\u00f3 que el 80% de la poblaci\u00f3n tiene esta bacteria y que este estudio busca comprender cu\u00e1les son los factores que se asocian a la infecci\u00f3n. Es por esto que el Hospital Base Valdivia invita a personas entre 1 y 69 a\u00f1os que residen entre las calles: General Lagos, Bueras, Pedro Montt y Baquedano a participar de la investigaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong>Proceso y aplicaci\u00f3n de encuesta<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">La Encuesta poblacional se est\u00e1 realizando mediante visitas domiciliarias de lunes a s\u00e1bado entre 9 y 20 horas. Las visitas las realizan cuatro encuestadoras capacitadas y con credenciales de identificaci\u00f3n validadas por el Servicio de Salud Valdivia.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">En una primera visita, se informa e invita a participar a las personas y familias. A quienes acepten, se les realizar\u00e1 una segunda visita para aplicar encuesta, tomar muestra de sangre y orina, y entregar el material para la toma de muestra de deposiciones que ser\u00e1n recogidas en una tercera visita.<\/p>\n<p style=\"text-align: justify;\">Una vez obtenidos los resultados de los ex\u00e1menes ser\u00e1n comunicados respetando la confidencialidad a las personas que resulten positivas a Hp. Adem\u00e1s de los resultados, se entregar\u00e1 informaci\u00f3n durante la encuesta (peso, talla, presi\u00f3n arterial).<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">El estudio pretende responder a las inquietudes planteadas en la investigaci\u00f3n y para ello estamos invitando a participar a familias o personas que residen en la ciudad de Valdivia, hasta completar una muestra de 700 personas entre las edades de 1 y 69 a\u00f1os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El proyecto consiste en una investigaci\u00f3n comparativa entre la ciudad de Valdivia y la ciudad de Antofagasta, con el objetivo de identificar la presencia de C\u00e1ncer G\u00e1strico asociado a la infecci\u00f3n por Helicobacter pylori, en ambas ciudades. \u00a0 \u00a0 La Unidad de Epidemiolog\u00eda del Hospital Base Valdivia en conjunto con la Pontificia Universidad Cat\u00f3lica de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":641,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[18],"tags":[],"class_list":["post-640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proyectos"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/foto-hp.jpg",1000,463,false],"thumbnail":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/foto-hp-150x150.jpg",150,150,true],"medium":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/foto-hp-300x139.jpg",300,139,true],"medium_large":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/foto-hp-768x356.jpg",768,356,true],"large":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/foto-hp.jpg",1000,463,false],"1536x1536":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/foto-hp.jpg",1000,463,false],"2048x2048":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/foto-hp.jpg",1000,463,false],"list_articles_thumbs":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/foto-hp-370x300.jpg",370,300,true],"slider_thumbs":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/foto-hp-432x200.jpg",432,200,true]},"uagb_author_info":{"display_name":"@dministrador","author_link":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/author\/dministrador\/"},"uagb_comment_info":0,"uagb_excerpt":"El proyecto consiste en una investigaci\u00f3n comparativa entre la ciudad de Valdivia y la ciudad de Antofagasta, con el objetivo de identificar la presencia de C\u00e1ncer G\u00e1strico asociado a la infecci\u00f3n por Helicobacter pylori, en ambas ciudades. \u00a0 \u00a0 La Unidad de Epidemiolog\u00eda del Hospital Base Valdivia en conjunto con la Pontificia Universidad Cat\u00f3lica de&hellip;","_links":{"self":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts\/640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/comments?post=640"}],"version-history":[{"count":2,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts\/640\/revisions"}],"predecessor-version":[{"id":643,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts\/640\/revisions\/643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/media\/641"}],"wp:attachment":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/media?parent=640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/categories?post=640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/tags?post=640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}