{"id":571,"date":"2016-05-13T21:26:21","date_gmt":"2016-05-13T21:26:21","guid":{"rendered":"http:\/\/10.6.67.9\/?p=571"},"modified":"2016-05-13T21:26:21","modified_gmt":"2016-05-13T21:26:21","slug":"seremi-y-director-promueven-diagnostico-precoz-para-prevenir-la-tuberculosis","status":"publish","type":"post","link":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/2016\/05\/13\/seremi-y-director-promueven-diagnostico-precoz-para-prevenir-la-tuberculosis\/","title":{"rendered":"SEREMI Y DIRECTOR promueven diagn\u00f3stico precoz para prevenir la Tuberculosis"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Con el objetivo de conmemorar el D\u00eda Mundial contra la Tuberculosis, la Mesa Intersectorial que encabeza la Seremi de Salud, realiz\u00f3 una jornada de prevenci\u00f3n en el \u00a0Hospital Base de Valdivia.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-572 aligncenter\" src=\"http:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/img_4249.jpg\" alt=\"img_4249\" width=\"720\" height=\"480\" srcset=\"https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/img_4249.jpg 720w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/img_4249-300x200.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/p>\n<p style=\"text-align: justify;\">Durante la actividad, el Seremi de Salud, Dr. Guillermo Ram\u00edrez y nuestro Director, conversaron con los usuarios sobre la importancia del diagn\u00f3stico precoz y la consulta frente a un cuadro respiratorio sostenido.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">El doctor Guillermo Ram\u00edrez, aclar\u00f3 que a\u00fan tenemos tuberculosis, una enfermedad que con los m\u00e9todos de diagn\u00f3stico precoz que tenemos, es posible de erradicar completamente al a\u00f1o 2020. Agreg\u00f3 que \u201cSi bien ha habido un control importante de la tuberculosis, \u00e9sta sigue teniendo una presencia en nuestra comunidad. Se trata de una enfermedad de lento avance que cuando se detecta en forma tard\u00eda, sus consecuencias no son las mejores. Por eso, existiendo hoy d\u00eda m\u00e9todos tan f\u00e1ciles de aplicar como la Baciloscop\u00eda, hacemos un llamado para que todas las personas que tengan un cuadro respiratorio se hagan este examen. Nuestra meta es llegar a cero tuberculosis el a\u00f1o 2020, lo que nos convoca a incrementar la cantidad de baciloscop\u00edas que estaremos realizando durante todo el a\u00f1o\u201d.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Por su parte el Dr. Luis Vera precis\u00f3 que \u201c\u00e9sta es una enfermedad que ha tenido una evoluci\u00f3n epidemiol\u00f3gica un poco err\u00e1tica el \u00faltimo tiempo, tenemos aproximadamente 50 pacientes diagnosticados el a\u00f1o 2014, con 4 fallecidos el a\u00f1o entre ellos, y esto se debe por una pesquisa tard\u00eda. \u00a0Por eso para nosotros es importante es seguir apostando a la consulta y diagn\u00f3stico precoz. Por supuesto nosotros estamos preparados para enfrentar esta patolog\u00eda, es importante que los hospitales de alta complejidad se sumen no solo en la parte curativa, tambi\u00e9n en la parte preventiva y promocional de los distintos temas\u201d.<\/p>\n<p style=\"text-align: justify;\">Durante la jornada en en el hall del policl\u00ednico de nuestro Hospital, la enfermera encargada del programa de tuberculosis de la Seremi de Salud, Carol Aracena, explic\u00f3 que \u201cmuchos piensan que esta es una patolog\u00eda del pasado, que hoy no existe, y lamentablemente s\u00ed tenemos casos en control o que tenemos que pesquisarlos a tiempo. Es importante que la gente sepa cu\u00e1les son los s\u00edntomas, el principal es tener tos por m\u00e1s de 15 d\u00edas y que soliciten el examen para detectar el bacilo\u201d.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong>DATOS<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">La mesa intersectorial de Tuberculosis sesiona desde el 24 de marzo del a\u00f1o 2014, y lo integran el Servicio de Salud Valdivia, el Hospital Base Valdivia, Gendarmer\u00eda de Chile \u00e1rea salud ASA Valdivia (concesionaria Centro penitenciario), y SEREMI de Salud.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong>El objetivo del Programa de Tuberculosis del Minsal es reducir al m\u00ednimo el riesgo de infecci\u00f3n, la morbilidad y mortalidad por Tuberculosis en Chile, hasta su eliminaci\u00f3n como problema de Salud<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el objetivo de conmemorar el D\u00eda Mundial contra la Tuberculosis, la Mesa Intersectorial que encabeza la Seremi de Salud, realiz\u00f3 una jornada de prevenci\u00f3n en el \u00a0Hospital Base de Valdivia. Durante la actividad, el Seremi de Salud, Dr. Guillermo Ram\u00edrez y nuestro Director, conversaron con los usuarios sobre la importancia del diagn\u00f3stico precoz y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":572,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[27],"tags":[],"class_list":["post-571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-campanas"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/img_4249.jpg",720,480,false],"thumbnail":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/img_4249-150x150.jpg",150,150,true],"medium":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/img_4249-300x200.jpg",300,200,true],"medium_large":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/img_4249.jpg",720,480,false],"large":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/img_4249.jpg",720,480,false],"1536x1536":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/img_4249.jpg",720,480,false],"2048x2048":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/img_4249.jpg",720,480,false],"list_articles_thumbs":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/img_4249-370x300.jpg",370,300,true],"slider_thumbs":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/05\/img_4249-300x200.jpg",300,200,true]},"uagb_author_info":{"display_name":"@dministrador","author_link":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/author\/dministrador\/"},"uagb_comment_info":0,"uagb_excerpt":"Con el objetivo de conmemorar el D\u00eda Mundial contra la Tuberculosis, la Mesa Intersectorial que encabeza la Seremi de Salud, realiz\u00f3 una jornada de prevenci\u00f3n en el \u00a0Hospital Base de Valdivia. Durante la actividad, el Seremi de Salud, Dr. Guillermo Ram\u00edrez y nuestro Director, conversaron con los usuarios sobre la importancia del diagn\u00f3stico precoz y&hellip;","_links":{"self":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts\/571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/comments?post=571"}],"version-history":[{"count":1,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts\/571\/revisions"}],"predecessor-version":[{"id":573,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts\/571\/revisions\/573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/media\/572"}],"wp:attachment":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/media?parent=571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/categories?post=571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/tags?post=571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}