{"id":2568,"date":"2017-08-03T19:00:07","date_gmt":"2017-08-03T22:00:07","guid":{"rendered":"https:\/\/www.hbvaldivia.cl\/portal\/?p=2568"},"modified":"2020-03-22T19:23:32","modified_gmt":"2020-03-22T22:23:32","slug":"hospital-base-valdivia-sumo-11-nuevos-sillones-de-hemodialisis-para-pacientes-con-patologias-nefrologicas","status":"publish","type":"post","link":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/2017\/08\/03\/hospital-base-valdivia-sumo-11-nuevos-sillones-de-hemodialisis-para-pacientes-con-patologias-nefrologicas\/","title":{"rendered":"Hospital Base Valdivia sum\u00f3 11 nuevos sillones de Hemodi\u00e1lisis para pacientes con patolog\u00edas nefrol\u00f3gicas"},"content":{"rendered":"<p style=\"text-align: justify\"><strong>Los nuevos equipos para el uso de hemodi\u00e1lisis poseen caracter\u00edsticas diferenciales para posiciones, ajuste y desplazamiento, con el objetivo de mejorar la calidad y seguridad de la atenci\u00f3n de los pacientes, as\u00ed como tambi\u00e9n la operatividad del usuario, aportando confort, practicidad y bioseguridad.<\/strong><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-2569 alignleft\" src=\"https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2017\/08\/dialisis-sillones-foto-300x181.jpg\" alt=\"\" width=\"300\" height=\"181\" srcset=\"https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2017\/08\/dialisis-sillones-foto-300x181.jpg 300w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2017\/08\/dialisis-sillones-foto-768x464.jpg 768w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2017\/08\/dialisis-sillones-foto-1024x619.jpg 1024w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2017\/08\/dialisis-sillones-foto-331x200.jpg 331w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: justify\">El proyecto, adjudicado por un monto de $34.243.440 pesos, fue gestionado con recursos propios del recinto, como parte de las acciones desplegadas por la Direcci\u00f3n Hospitalaria para responder a los requerimientos de atenci\u00f3n de salud de los m\u00e1s de 130 pacientes con patolog\u00edas nefrol\u00f3gicas, provenientes de diversas comunas de la regi\u00f3n de Los R\u00edos, que se atienden en la Unidad de Hemodi\u00e1lisis del Hospital Base Valdivia, \u00fanico centro asistencial de alta complejidad de la regi\u00f3n.<\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<p style=\"text-align: justify\">Jos\u00e9 Luis Riquelme, paciente del Hospital Base, agradece la nueva implementaci\u00f3n para la Unidad de Di\u00e1lisis, \u201cpara m\u00ed ha sido extraordinario la llegada de los sillones nuevos para di\u00e1lisis, porque muchas veces la posici\u00f3n que ten\u00edan los sillones antiguos no nos permit\u00edan acomodarnos de la mejor manera, y produc\u00eda que estuvi\u00e9ramos requiriendo constantemente de los servicios del personal de Di\u00e1lisis. Esto ha sido maravilloso, tener la posibilidad de uno mismo poder controlar la posici\u00f3n del sill\u00f3n\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Los nuevos equipos est\u00e1n dise\u00f1ados en cuatro secciones: cuerpo, brazos, piernas y piecera; con controles de posici\u00f3n autom\u00e1ticos, apoya brazos y ajuste de altura para facilitar el acceso a personas con movilidad reducida, para manejo a comodidad del usuario. Otra de sus caracter\u00edsticas, es disponer de una mesa plegable multiprop\u00f3sito adosada al sill\u00f3n, adem\u00e1s un ajuste de forma independiente para cada secci\u00f3n, permitiendo los movimientos independientes del respaldo, del asiento y de la zona de las piernas del paciente.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los nuevos equipos para el uso de hemodi\u00e1lisis poseen caracter\u00edsticas diferenciales para posiciones, ajuste y desplazamiento, con el objetivo de mejorar la calidad y seguridad de la atenci\u00f3n de los pacientes, as\u00ed como tambi\u00e9n la operatividad del usuario, aportando confort, practicidad y bioseguridad. El proyecto, adjudicado por un monto de $34.243.440 pesos, fue gestionado con [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2570,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[11,53,18],"tags":[],"class_list":["post-2568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-adquisiciones","category-gestiones","category-proyectos"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2017\/08\/SLIDER-dialisis-sillones-foto.jpg",496,300,false],"thumbnail":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2017\/08\/SLIDER-dialisis-sillones-foto-150x150.jpg",150,150,true],"medium":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2017\/08\/SLIDER-dialisis-sillones-foto-300x181.jpg",300,181,true],"medium_large":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2017\/08\/SLIDER-dialisis-sillones-foto.jpg",496,300,false],"large":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2017\/08\/SLIDER-dialisis-sillones-foto.jpg",496,300,false],"1536x1536":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2017\/08\/SLIDER-dialisis-sillones-foto.jpg",496,300,false],"2048x2048":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2017\/08\/SLIDER-dialisis-sillones-foto.jpg",496,300,false],"list_articles_thumbs":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2017\/08\/SLIDER-dialisis-sillones-foto-370x300.jpg",370,300,true],"slider_thumbs":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2017\/08\/SLIDER-dialisis-sillones-foto-331x200.jpg",331,200,true]},"uagb_author_info":{"display_name":"Nicolina Lagomarsino","author_link":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/author\/nlagomarsino\/"},"uagb_comment_info":0,"uagb_excerpt":"Los nuevos equipos para el uso de hemodi\u00e1lisis poseen caracter\u00edsticas diferenciales para posiciones, ajuste y desplazamiento, con el objetivo de mejorar la calidad y seguridad de la atenci\u00f3n de los pacientes, as\u00ed como tambi\u00e9n la operatividad del usuario, aportando confort, practicidad y bioseguridad. El proyecto, adjudicado por un monto de $34.243.440 pesos, fue gestionado con&hellip;","_links":{"self":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts\/2568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/comments?post=2568"}],"version-history":[{"count":2,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts\/2568\/revisions"}],"predecessor-version":[{"id":2580,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts\/2568\/revisions\/2580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/media\/2570"}],"wp:attachment":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/media?parent=2568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/categories?post=2568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/tags?post=2568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}