{"id":1474,"date":"2016-10-20T11:43:48","date_gmt":"2016-10-20T14:43:48","guid":{"rendered":"http:\/\/www.hbvaldivia.cl\/portal\/?p=1474"},"modified":"2017-01-25T11:49:10","modified_gmt":"2017-01-25T14:49:10","slug":"hospital-base-de-valdivia-conmemora-9-semana-de-lucha-contra-el-cancer","status":"publish","type":"post","link":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/2016\/10\/20\/hospital-base-de-valdivia-conmemora-9-semana-de-lucha-contra-el-cancer\/","title":{"rendered":"Hospital Base de Valdivia conmemora 9\u00b0 semana de Lucha contra el C\u00e1ncer"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Con actividades de Prevenci\u00f3n en patolog\u00edas oncol\u00f3gicas\u00a0 y \u00a0promoci\u00f3n de vida saludable, el Subdepartamento de Oncolog\u00eda y Radioterapia del Hospital Base conmemora la 9\u00b0 Semana Mundial de Lucha contra el C\u00e1ncer en Valdivia.<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\n<img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-1476 alignleft\" src=\"http:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/10\/lucha_contra_cancer_valdivia.jpg\" alt=\"lucha_contra_cancer_valdivia\" width=\"429\" height=\"320\" srcset=\"https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/10\/lucha_contra_cancer_valdivia.jpg 638w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/10\/lucha_contra_cancer_valdivia-300x224.jpg 300w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/10\/lucha_contra_cancer_valdivia-268x200.jpg 268w\" sizes=\"(max-width: 429px) 100vw, 429px\" \/>Con el objetivo de contribuir en el cumplimiento del objetivo sanitario del Ministerio de Salud de \u201cReducir la tasa proyectada de mortalidad por c\u00e1ncer en un 5% al 2020\u201d, se conmemora cada mes de octubre la \u201cSemana de Lucha contra el C\u00e1ncer\u201d, contenida en la Estrategia Nacional de Salud ENS 2011-2020.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">En este sentido, el Hospital Base Valdivia a trav\u00e9s del Subdepartamento de Oncolog\u00eda y Radioterapia , lider\u00f3 la <strong>\u201cFeria Educativa de Prevenci\u00f3n del C\u00e1ncer\u201d <\/strong>con stands informativos sobre prevenci\u00f3n y detecci\u00f3n precoz de C\u00e1ncer de Mama, C\u00e1ncer Cervico Uterino, C\u00e1ncer G\u00e1strico, Tumores S\u00f3lidos y Hematol\u00f3gicos, Alimentaci\u00f3n Saludable, y tratamientos de Quimioterapia y Radioterapia.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Esta actividad, es parte de la campa\u00f1a de comunicaci\u00f3n social dirigida a la comunidad para \u201csensibilizar a la poblaci\u00f3n en su conjunto, informando sobre el c\u00e1ncer y posicionando la promoci\u00f3n de la salud para impulsar el control de factores de riesgo, favorecer el autocuidado y contribuir a reducir la incidencia a trav\u00e9s de la detecci\u00f3n precoz y la aplicaci\u00f3n de tratamientos oportunos\u201d.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\nLidia Dur\u00e1n, Asistente Social del Subdepartamento de Oncolog\u00eda mencion\u00f3 que este Subdepto \u201chace a\u00f1os viene participando con diversas actividades de Promoci\u00f3n y Prevenci\u00f3n dirigidas a la poblaci\u00f3n valdiviana, con el fin de dar a conocer que contamos con uno de los 6 centros oncol\u00f3gicos de Radioterapia del Pa\u00eds\u201d.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong>Las actividades de este a\u00f1o se realizaron el mi\u00e9rcoles 19 desde las 9:00 hasta las 13:00 horas, en el Hall de ingreso por Calle Bueras y como es tradici\u00f3n, los usuarios pudieron realizar consultas a los equipos multidisciplinarios conformados por\u00a0 m\u00e9dicos, enfermeros\/as,\u00a0 matronas\/es,\u00a0 T\u00e9cnicos en Enfermer\u00eda, y equipos de apoyo de nuestro Hospital.<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"wp-image-1475 alignright\" src=\"http:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/10\/feria_cancer_hospital_valdivia.jpg\" alt=\"feria_cancer_hospital_valdivia\" width=\"227\" height=\"273\" srcset=\"https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/10\/feria_cancer_hospital_valdivia.jpg 640w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/10\/feria_cancer_hospital_valdivia-249x300.jpg 249w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/10\/feria_cancer_hospital_valdivia-166x200.jpg 166w\" sizes=\"(max-width: 227px) 100vw, 227px\" \/>\u201cAdem\u00e1s realizaremos pausas saludables de m\u00fasica, baile entretenido, pintura de m\u00e1ndalas, masajes anti estr\u00e9s y mucho m\u00e1s, por lo que invitamos a la comunidad a acompa\u00f1arnos\u201d, afirm\u00f3 Lidia Dur\u00e1n, Asistente Social de HBV<\/p>\n<p style=\"text-align: justify;\"><strong><em>Uno de los \u00e9nfasis de la \u201cNOVENA SEMANA DE LA LUCHA CONTRA EL C\u00c1NCER\u201d es el llamado a detectar el c\u00e1ncer de mama, recordando la importancia de contar con la mamograf\u00eda vigente (minsal, 2016).<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\nEsta actividad se enmarca en un calendario de charlas, talleres, ferias de promoci\u00f3n y actividades destinadas a promover estilos de vida sanos y con ello prevenir los diferentes tipos de c\u00e1ncer que afectan a la poblaci\u00f3n por parte de la Seremi de Salud de la Regi\u00f3n de Los R\u00edos.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con actividades de Prevenci\u00f3n en patolog\u00edas oncol\u00f3gicas\u00a0 y \u00a0promoci\u00f3n de vida saludable, el Subdepartamento de Oncolog\u00eda y Radioterapia del Hospital Base conmemora la 9\u00b0 Semana Mundial de Lucha contra el C\u00e1ncer en Valdivia. \u00a0 Con el objetivo de contribuir en el cumplimiento del objetivo sanitario del Ministerio de Salud de \u201cReducir la tasa proyectada de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1477,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[27],"tags":[],"class_list":["post-1474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-campanas"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/10\/Semana_lucha_cancer_hospital.jpg",640,459,false],"thumbnail":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/10\/Semana_lucha_cancer_hospital-150x150.jpg",150,150,true],"medium":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/10\/Semana_lucha_cancer_hospital-300x215.jpg",300,215,true],"medium_large":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/10\/Semana_lucha_cancer_hospital.jpg",640,459,false],"large":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/10\/Semana_lucha_cancer_hospital.jpg",640,459,false],"1536x1536":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/10\/Semana_lucha_cancer_hospital.jpg",640,459,false],"2048x2048":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/10\/Semana_lucha_cancer_hospital.jpg",640,459,false],"list_articles_thumbs":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/10\/Semana_lucha_cancer_hospital-370x300.jpg",370,300,true],"slider_thumbs":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2016\/10\/Semana_lucha_cancer_hospital-279x200.jpg",279,200,true]},"uagb_author_info":{"display_name":"@dministrador","author_link":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/author\/dministrador\/"},"uagb_comment_info":0,"uagb_excerpt":"Con actividades de Prevenci\u00f3n en patolog\u00edas oncol\u00f3gicas\u00a0 y \u00a0promoci\u00f3n de vida saludable, el Subdepartamento de Oncolog\u00eda y Radioterapia del Hospital Base conmemora la 9\u00b0 Semana Mundial de Lucha contra el C\u00e1ncer en Valdivia. \u00a0 Con el objetivo de contribuir en el cumplimiento del objetivo sanitario del Ministerio de Salud de \u201cReducir la tasa proyectada de&hellip;","_links":{"self":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts\/1474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/comments?post=1474"}],"version-history":[{"count":5,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts\/1474\/revisions"}],"predecessor-version":[{"id":2120,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts\/1474\/revisions\/2120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/media\/1477"}],"wp:attachment":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/media?parent=1474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/categories?post=1474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/tags?post=1474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}