{"id":10683,"date":"2026-03-24T09:34:17","date_gmt":"2026-03-24T12:34:17","guid":{"rendered":"http:\/\/10.6.206.88\/portal\/?p=10683"},"modified":"2026-03-26T11:21:59","modified_gmt":"2026-03-26T14:21:59","slug":"dr-luis-ebel-sepulveda-jefe-del-servicio-de-urologia-del-hbv-seremos-el-primer-hospital-publico-del-sur-en-contar-con-cirugia-robotica","status":"publish","type":"post","link":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/2026\/03\/24\/dr-luis-ebel-sepulveda-jefe-del-servicio-de-urologia-del-hbv-seremos-el-primer-hospital-publico-del-sur-en-contar-con-cirugia-robotica\/","title":{"rendered":"Dr. Luis Ebel Sep\u00falveda, jefe del Servicio de Urolog\u00eda del HBV: \u00abSeremos el primer hospital p\u00fablico del sur en contar con cirug\u00eda rob\u00f3tica&#8230;\u00bb"},"content":{"rendered":"<ul>\n<li><strong><em>Destacado m\u00e9dico hizo un repaso por su trayectoria acad\u00e9mica y profesional, resalt\u00f3 hitos fundamentales en el desarrollo de la urolog\u00eda a nivel local, y tambi\u00e9n enumer\u00f3 los principales desaf\u00edos en el corto y mediano plazo.<\/em><\/strong><\/li>\n<\/ul>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-10692 size-full\" src=\"http:\/\/10.6.206.88\/portal\/wp-content\/uploads\/2026\/03\/Dra.-Marianela-Rubilar-Gomez-saluda-cordialmente-14.png\" alt=\"\" width=\"1748\" height=\"1240\" srcset=\"https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/Dra.-Marianela-Rubilar-Gomez-saluda-cordialmente-14.png 1748w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/Dra.-Marianela-Rubilar-Gomez-saluda-cordialmente-14-300x213.png 300w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/Dra.-Marianela-Rubilar-Gomez-saluda-cordialmente-14-1024x726.png 1024w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/Dra.-Marianela-Rubilar-Gomez-saluda-cordialmente-14-1536x1090.png 1536w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/Dra.-Marianela-Rubilar-Gomez-saluda-cordialmente-14-282x200.png 282w\" sizes=\"(max-width: 1748px) 100vw, 1748px\" \/><\/p>\n<p style=\"text-align: justify;\">Un a\u00f1o como jefe del Servicio de Urolog\u00eda del Hospital Base Valdivia, suma actualmente el <strong>m\u00e9dico especialista Luis Ebel Sep\u00falveda<\/strong>, quien a su vez registra casi tres d\u00e9cadas de experiencia profesional en el principal establecimiento de salud de la regi\u00f3n de Los R\u00edos.<\/p>\n<p style=\"text-align: justify;\">Junto con hacer un repaso por su trayectoria acad\u00e9mica y laboral, el profesional dio a conocer los principales avances de la especialidad a nivel local, as\u00ed como tambi\u00e9n revel\u00f3 los principales desaf\u00edos que tiene el Servicio de Urolog\u00eda en el corto y mediano plazo.<\/p>\n<p style=\"text-align: justify;\">Luis Ebel Sep\u00falveda tiene 61 a\u00f1os de edad y naci\u00f3 el 10 de noviembre de 1964 en la ciudad de Puerto Montt, regi\u00f3n de Los Lagos. Curs\u00f3 su ense\u00f1anza b\u00e1sica y media en el Instituto Alem\u00e1n de Puerto Montt, y posteriormente entr\u00f3 a estudiar medicina en la Universidad Cat\u00f3lica de Chile, en la regi\u00f3n Metropolitana.<\/p>\n<p style=\"text-align: justify;\">Con respecto a su elecci\u00f3n profesional explic\u00f3: \u00abDesde chico siempre me llam\u00f3 la atenci\u00f3n la medicina, en ese entonces m\u00e1s asociada a la biolog\u00eda y anatom\u00eda. Creo que influy\u00f3 mucho en mi formaci\u00f3n un profesor de biolog\u00eda que tuve, que era muy estudioso y muy buen docente. Eso permiti\u00f3 complementar mi inter\u00e9s, mi vocaci\u00f3n, por lo que en la ense\u00f1anza media ya ten\u00eda claro que quer\u00eda ser m\u00e9dico\u00bb.<\/p>\n<p style=\"text-align: justify;\">Con respecto a su especialidad en urolog\u00eda, la curs\u00f3 en el Programa de Especializaci\u00f3n en Urolog\u00eda de la Universidad Austral de Chile. \u00abEstando en quinto a\u00f1o de la universidad (Cat\u00f3lica), tuve un profesor que hac\u00eda el curso de urolog\u00eda, y que influy\u00f3 mucho como maestro en esa etapa de mi vida, que era el doctor Pedro Mart\u00ednez. Hice el internado de urolog\u00eda en la Cat\u00f3lica, y cuando termin\u00e9 la carrera me fui de m\u00e9dico general de zona a Coyhaique donde trabaj\u00e9 por cinco a\u00f1os, pero siempre queriendo volver a hacer la beca de urolog\u00eda. Este centro formador de Valdivia tiene mucho prestigio, y como quer\u00eda seguir mi vida en el sur, me vine para hacer mi formaci\u00f3n entre 1996 y 1999\u00bb, explic\u00f3 al respecto.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00bfC\u00f3mo definir\u00eda usted la especialidad de urolog\u00eda?<\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Es una especialidad que se ocupa de las enfermedades del aparato genitourinario, que es el aparato que produce la orina, y que incluye ri\u00f1ones, ur\u00e9ter, vejiga, pr\u00f3stata en el hombre, y tambi\u00e9n de los genitales masculinos, ya que de los genitales femeninos se ocupa la ginecolog\u00eda.<\/p>\n<p style=\"text-align: justify;\">Es una especialidad m\u00e9dico quir\u00fargica, donde no s\u00f3lo nos dedicamos a operar pacientes, sino que tambi\u00e9n nos dedicamos al tratamiento de enfermedades que son m\u00e9dicas muchas veces, y no quir\u00fargicas. Por lo tanto, atendemos hombres, tambi\u00e9n mujeres, y tambi\u00e9n hay ur\u00f3logos que se dedican a la urolog\u00eda infantil. En el caso del Hospital Base Valdivia, s\u00f3lo vemos urolog\u00eda del adulto, que son pacientes mayores de 15 a\u00f1os de edad.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00bfQu\u00e9 puede comentar sobre los or\u00edgenes, evoluci\u00f3n e hitos del Servicio de Urolog\u00eda del HBV?<\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">En relaci\u00f3n a los inicios de la urolog\u00eda en el Hospital Base Valdivia, tenemos que colocar en primera l\u00ednea al doctor Dante Corti, que es como el padre de la urolog\u00eda en nuestra regi\u00f3n. Lleg\u00f3 a Valdivia en 1967, y dos a\u00f1os despu\u00e9s ingres\u00f3 al Servicio de Urolog\u00eda que ya estaba formado en el Hospital Base, pero que \u00e9l lo potenci\u00f3 y desarroll\u00f3 en todo aspecto. Fue el jefe de Servicio hasta el a\u00f1o 2017, per\u00edodo en el cual tambi\u00e9n trabaj\u00f3 como docente de la Facultad de Medicina de la UACh. Desde 1976 desarroll\u00f3 el programa de especializaci\u00f3n en Urolog\u00eda, que a la fecha ha permitido formar 44 ur\u00f3logos.<\/p>\n<p style=\"text-align: justify;\">Durante estos a\u00f1os ha habido otros importantes hitos en el desarrollo de esta especialidad, como el inicio del Programa de Trasplante Renal, que parti\u00f3 en 1980 y fue pionero en el sur del pa\u00eds, y a la fecha tenemos 599 trasplantes renales. Otro de los hitos tiene relaci\u00f3n con la parte oncol\u00f3gica, ya que nuestro Servicio se ha destacado en el diagn\u00f3stico, tratamiento y seguimiento de las enfermedades oncol\u00f3gicas urol\u00f3gicas, que son principalmente el c\u00e1ncer de ri\u00f1\u00f3n, de pr\u00f3stata, de vejiga, y el c\u00e1ncer testicular.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00bfCu\u00e1l es el rol del equipo de urolog\u00eda en el trasplante renal?<\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">El equipo del Servicio de Urolog\u00eda est\u00e1 conformado por siete ur\u00f3logos (seis hombres y una mujer), que tambi\u00e9n trabajan d\u00eda a d\u00eda con m\u00e9dicos que est\u00e1n en formaci\u00f3n. Adem\u00e1s nuestro equipo lo componen una enfermera, dos t\u00e9cnicos en enfermer\u00eda, una secretaria y un auxiliar de servicio.<\/p>\n<p style=\"text-align: justify;\">Nosotros participamos del Programa de Trasplante Renal del Hospital Base Valdivia, en que tambi\u00e9n participa el Servicio de Nefrolog\u00eda, por lo que es un equipo de nefrourolog\u00eda que se dedica a este programa. Es una cirug\u00eda que desarrollamos hace mucho tiempo, vamos a cumplir pronto los 600 trasplantes, y somos el centro de referencia de la macrozona desde Valdivia al sur.<\/p>\n<p style=\"text-align: justify;\">Muchas veces nos llegan pacientes que son candidatos a trasplante, que por alguna condici\u00f3n urol\u00f3gica hay que evaluarlos antes del trasplante, para que una vez cumplidos todos los requisitos, puedan ingresar a la lista de espera. Adem\u00e1s, somos los cirujanos que ejecutamos el trasplante, y posteriormente tenemos que participar en el seguimiento y post operatorio de estos pacientes. Por lo tanto, nos toca participar en todas las etapas del trasplante renal, en la selecci\u00f3n de los pacientes, en la cirug\u00eda y en el seguimiento posterior.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00bfCu\u00e1les son las principales patolog\u00edas oncol\u00f3gicas y cu\u00e1les han sido los principales avances en diagn\u00f3stico y tratamiento?<\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Lo que vemos en mayor n\u00famero es el c\u00e1ncer de pr\u00f3stata, seguido por el c\u00e1ncer de ri\u00f1\u00f3n y c\u00e1ncer de test\u00edculo, y en cuarto lugar aparece el c\u00e1ncer de vejiga. Para el tratamiento de ellos, disponemos de casi todas las alternativas existentes, ya que todas estas patolog\u00edas est\u00e1n consideradas dentro del Programa GES.<\/p>\n<p style=\"text-align: justify;\">El Hospital Base Valdivia dispone de toda la tecnolog\u00eda para diagnosticar y seguir a estos pacientes.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00bfCu\u00e1les son las principales alternativas para conseguir un diagn\u00f3stico precoz de este tipo de patolog\u00edas?<\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Entre estas patolog\u00edas, las que cuentan con ex\u00e1menes de diagn\u00f3stico precoz, est\u00e1 el c\u00e1ncer de pr\u00f3stata, ya que se considera iniciar un control rutinario de todos los hombres a partir de los 50 a\u00f1os de edad. Para el c\u00e1ncer testicular, actualmente estamos en una campa\u00f1a que se denomina \u00abT\u00f3cate Los R\u00edos\u00bb, para promover el autoexamen testicular, y conozcan la enfermedad.<\/p>\n<p style=\"text-align: justify;\">En el caso del c\u00e1ncer de vejiga no hay estrategias de detecci\u00f3n temprana, sino que m\u00e1s bien de educaci\u00f3n en cuanto al v\u00ednculo del tabaquismo con la aparici\u00f3n de c\u00e1ncer vesical. Con respecto al c\u00e1ncer de ri\u00f1\u00f3n, lo que uno recomienda es que hombres y mujeres se hagan una ecograf\u00eda abdominal por la eventualidad de que pudiese pesquisarse una patolog\u00eda de este tipo.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00bfEn qu\u00e9 consiste el proyecto de cirug\u00eda rob\u00f3tica que impulsa el Servicio de Urolog\u00eda del HBV?<\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Como instituci\u00f3n estamos muy contentos porque hay un proyecto de cirug\u00eda rob\u00f3tica para nuestro hospital, que se inici\u00f3 hace tres a\u00f1os y que ha ido cumpliendo diferentes etapas. Aparentemente, este proyecto ver\u00e1 la luz en una fecha cercana, lo cual ser\u00eda un tremendo aporte al trabajo, especialmente en el manejo de la patolog\u00eda oncol\u00f3gica, pero no s\u00f3lo urolog\u00eda, sino que tambi\u00e9n para cirug\u00eda digestiva, cirug\u00eda infantil, y ginecolog\u00eda, por lo que hay una serie de especialidades que se van a beneficiar de este proyecto impulsado por el Servicio de Urolog\u00eda.<\/p>\n<p style=\"text-align: justify;\">Hemos tenido un gran apoyo de la direcci\u00f3n del Hospital Base, del Gobierno Regional y el Consejo Regional, que han entendido que esta es una necesidad de mejorar la atenci\u00f3n de salud de nuestros pacientes, sobre todo porque se trata de un centro de referencia oncol\u00f3gica como es el Hospital Base Valdivia, que adem\u00e1s es un centro docente al alero de la Universidad Austral de Chile.<\/p>\n<p style=\"text-align: justify;\">Este proyecto permitir\u00e1 mejorar la atenci\u00f3n de nuestros usuarios, y por otra parte ser\u00e1 un aporte al desarrollo acad\u00e9mico y profesional de los m\u00e9dicos en formaci\u00f3n.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00bfCu\u00e1les son los beneficios que tiene la cirug\u00eda rob\u00f3tica?<\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Es importante destacar que la cirug\u00eda rob\u00f3tica en Chile parti\u00f3 en el a\u00f1o 2009 en la Cl\u00ednica Indisa en Santiago, y de ah\u00ed se han ido sumando principalmente instituciones privadas en la regi\u00f3n Metropolitana. Hasta hace dos o tres a\u00f1os esa era la realidad, hasta que se desarroll\u00f3 un proyecto muy interesante en el Hospital San Borja Arriar\u00e1n, que fue el primer recinto p\u00fablico en tener cirug\u00eda rob\u00f3tica. El a\u00f1o pasado se sum\u00f3 el Hospital F\u00e9lix Bulnes, por lo que nosotros ser\u00edamos el primer establecimiento p\u00fablico del sur en contar con esta tecnolog\u00eda, ya que tambi\u00e9n existe un proyecto similar en el Hospital de La Serena. Esto nos llena de orgullo, porque esto ha requerido mucho trabajo conjunto entre la parte m\u00e9dica y administrativa, para llevar a cabo este proyecto.<\/p>\n<p style=\"text-align: justify;\">El beneficio para los pacientes tiene relaci\u00f3n con que las cirug\u00edas son con menos agresi\u00f3n quir\u00fargica, no se hace una incisi\u00f3n, sino que es una t\u00e9cnica m\u00ednimamente invasiva, ya que se accede a la cirug\u00eda por peque\u00f1os portales donde ingresar los instrumentos. Como la agresi\u00f3n quir\u00fargica es mucho menor, la recuperaci\u00f3n es m\u00e1s r\u00e1pida, ya que los pacientes sangran menos y tambi\u00e9n requieren menos uso de transfusiones. Tambi\u00e9n les duele menos, por lo que usan menos analg\u00e9sicos y antiinflamatorios, por lo que se pueden reincorporar m\u00e1s r\u00e1pido a sus actividades.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n se ha visto que hay una mejor\u00eda de los resultados, en comparaci\u00f3n a una cirug\u00eda tradicional abierta.<\/p>\n<p style=\"text-align: justify;\">La cirug\u00eda rob\u00f3tica implica tambi\u00e9n un avance mayor a la cirug\u00eda laparosc\u00f3pica, que tambi\u00e9n es m\u00ednimamente invasiva, y tambi\u00e9n se desarrolla ampliamente en nuestro hospital. Claramente este es un avance tecnol\u00f3gico para nuestra instituci\u00f3n, acad\u00e9mico; pero lo m\u00e1s importante es un avance para nuestros pacientes.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>Adem\u00e1s de la cirug\u00eda rob\u00f3tica, \u00bfcu\u00e1les son los principales desaf\u00edos que tiene actualmente el Servicio de Urolog\u00eda del HBV?<\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Como equipo hoy somos un grupo en etapa de recambio, tenemos un grupo de ur\u00f3logos muy j\u00f3venes, con muchas ganas de desarrollarse a\u00fan m\u00e1s en la urolog\u00eda.<\/p>\n<p style=\"text-align: justify;\">Indudablemente que el proyecto de cirug\u00eda rob\u00f3tica es un desaf\u00edo para nosotros en el futuro inmediato, pero la urolog\u00eda igualmente trata otras patolog\u00edas m\u00e1s all\u00e1 del c\u00e1ncer, que tambi\u00e9n requieren de un desarrollo tecnol\u00f3gico, como por ejemplo el manejo de los c\u00e1lculos urinarios, de lo cual tambi\u00e9n hemos podido acceder a tecnolog\u00eda de punta.<\/p>\n<p style=\"text-align: justify;\">Por ejemplo, queremos desarrollar la endourolog\u00eda, que tiene que ver con el tratamiento de los c\u00e1lculos renales, pero tambi\u00e9n con la cirug\u00eda prost\u00e1tica. Ah\u00ed tenemos un desaf\u00edo importante en el desarrollo de la cirug\u00eda l\u00e1ser, que ya la estamos incorporando, pero queremos mejorar nuestros equipos y tratar en lo posible hacer una cirug\u00eda con una estad\u00eda hospitalaria m\u00e1s corta, para que el paciente se reincorpore m\u00e1s r\u00e1pido a sus actividades y tenga menos complicaciones.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n tenemos un proyecto de desarrollo de cirug\u00eda de piso p\u00e9lvico, en que tratamos principalmente a mujer con desarrollo de cirug\u00edas del uso de pr\u00f3tesis.<\/p>\n<p style=\"text-align: justify;\">Finalmente, una cuarta \u00e1rea de desarrollo tiene que ver con potenciar la androlog\u00eda, una subespecialidad que a futuro queremos potenciar. Adem\u00e1s, por supuesto, queremos continuar fortaleciendo lo que ya venimos haciendo.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p><strong>Entrevista realizada por Diarioaustral de Los R\u00edos.<\/strong><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-large wp-image-10686\" src=\"http:\/\/10.6.206.88\/portal\/wp-content\/uploads\/2026\/03\/equipo-urologia-1024x673.jpeg\" alt=\"\" width=\"1024\" height=\"673\" srcset=\"https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/equipo-urologia-1024x673.jpeg 1024w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/equipo-urologia-300x197.jpeg 300w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/equipo-urologia-304x200.jpeg 304w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/equipo-urologia.jpeg 1170w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-large wp-image-10687\" src=\"http:\/\/10.6.206.88\/portal\/wp-content\/uploads\/2026\/03\/IMG_0856-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/IMG_0856-1024x683.jpg 1024w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/IMG_0856-300x200.jpg 300w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/IMG_0856-1536x1024.jpg 1536w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/IMG_0856-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-10688\" src=\"http:\/\/10.6.206.88\/portal\/wp-content\/uploads\/2026\/03\/IMG_0849-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/IMG_0849-1024x683.jpg 1024w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/IMG_0849-300x200.jpg 300w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/IMG_0849-1536x1024.jpg 1536w, https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/IMG_0849-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Destacado m\u00e9dico hizo un repaso por su trayectoria acad\u00e9mica y profesional, resalt\u00f3 hitos fundamentales en el desarrollo de la urolog\u00eda a nivel local, y tambi\u00e9n enumer\u00f3 los principales desaf\u00edos en el corto y mediano plazo. Un a\u00f1o como jefe del Servicio de Urolog\u00eda del Hospital Base Valdivia, suma actualmente el m\u00e9dico especialista Luis Ebel Sep\u00falveda, [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":10692,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-10683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/Dra.-Marianela-Rubilar-Gomez-saluda-cordialmente-14.png",1748,1240,false],"thumbnail":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/Dra.-Marianela-Rubilar-Gomez-saluda-cordialmente-14-150x150.png",150,150,true],"medium":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/Dra.-Marianela-Rubilar-Gomez-saluda-cordialmente-14-300x213.png",300,213,true],"medium_large":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/Dra.-Marianela-Rubilar-Gomez-saluda-cordialmente-14.png",1748,1240,false],"large":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/Dra.-Marianela-Rubilar-Gomez-saluda-cordialmente-14-1024x726.png",1024,726,true],"1536x1536":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/Dra.-Marianela-Rubilar-Gomez-saluda-cordialmente-14-1536x1090.png",1536,1090,true],"2048x2048":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/Dra.-Marianela-Rubilar-Gomez-saluda-cordialmente-14.png",1748,1240,false],"list_articles_thumbs":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/Dra.-Marianela-Rubilar-Gomez-saluda-cordialmente-14-400x400.png",400,400,true],"slider_thumbs":["https:\/\/www.hbvaldivia.cl\/portal\/wp-content\/uploads\/2026\/03\/Dra.-Marianela-Rubilar-Gomez-saluda-cordialmente-14-282x200.png",282,200,true]},"uagb_author_info":{"display_name":"Barbara Vega","author_link":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/author\/barbara-vega-ssvredsalud-gob-cl\/"},"uagb_comment_info":0,"uagb_excerpt":"Destacado m\u00e9dico hizo un repaso por su trayectoria acad\u00e9mica y profesional, resalt\u00f3 hitos fundamentales en el desarrollo de la urolog\u00eda a nivel local, y tambi\u00e9n enumer\u00f3 los principales desaf\u00edos en el corto y mediano plazo. Un a\u00f1o como jefe del Servicio de Urolog\u00eda del Hospital Base Valdivia, suma actualmente el m\u00e9dico especialista Luis Ebel Sep\u00falveda,&hellip;","_links":{"self":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts\/10683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/comments?post=10683"}],"version-history":[{"count":7,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts\/10683\/revisions"}],"predecessor-version":[{"id":10707,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/posts\/10683\/revisions\/10707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/media\/10692"}],"wp:attachment":[{"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/media?parent=10683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/categories?post=10683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hbvaldivia.cl\/portal\/index.php\/wp-json\/wp\/v2\/tags?post=10683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}